{"id":154,"date":"2019-11-19T16:53:30","date_gmt":"2019-11-19T15:53:30","guid":{"rendered":"https:\/\/mfhohenlimburg.de\/wordpress\/?page_id=154"},"modified":"2019-11-23T23:28:04","modified_gmt":"2019-11-23T22:28:04","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/mfhohenlimburg.de\/wordpress\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full wpforms-block\" id=\"wpforms-152\"><form id=\"wpforms-form-152\" class=\"wpforms-validate wpforms-form\" data-formid=\"152\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/wordpress\/wp-json\/wp\/v2\/pages\/154\" data-token=\"2b131c514a263c33336a7a271466ef0e\" data-token-time=\"1784154965\"><noscript class=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-152-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\">Name<\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-152-field_0\" class=\"wpforms-field-name-first\" name=\"wpforms[fields][0][first]\" ><label for=\"wpforms-152-field_0\" class=\"wpforms-field-sublabel after\">Vorname<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-152-field_0-last\" class=\"wpforms-field-name-last\" name=\"wpforms[fields][0][last]\" ><label for=\"wpforms-152-field_0-last\" class=\"wpforms-field-sublabel after\">Nachname<\/label><\/div><\/div><\/div><div id=\"wpforms-152-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-152-field_1\">E-Mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-152-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-152-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-152-field_2\">Kommentar oder Nachricht <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-152-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><div id=\"wpforms-152-field_3-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"3\"><ul id=\"wpforms-152-field_3\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-152-field_3_1\" name=\"wpforms[fields][3][]\" value=\"Sie erkl\u00e4ren sich damit einverstanden, dass Ihre Daten zur Bearbeitung Ihres Anliegends verwendet werden. Informationen und Widerrufshinweise finden Sie in der Datenschutzerkl\u00e4rung.\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-152-field_3_1\">Sie erkl\u00e4ren sich damit einverstanden, dass Ihre Daten zur Bearbeitung Ihres Anliegends verwendet werden. Informationen und Widerrufshinweise finden Sie in der Datenschutzerkl\u00e4rung.<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-152-field-hp\" class=\"wpforms-field-label\">Comment<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-152-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"152\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mfhohenlimburg.de\/wordpress\/wp-json\/wp\/v2\/pages\/154\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-152\" class=\"wpforms-submit\" data-alt-text=\"Senden...\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-154","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mfhohenlimburg.de\/wordpress\/wp-json\/wp\/v2\/pages\/154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfhohenlimburg.de\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mfhohenlimburg.de\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mfhohenlimburg.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mfhohenlimburg.de\/wordpress\/wp-json\/wp\/v2\/comments?post=154"}],"version-history":[{"count":2,"href":"https:\/\/mfhohenlimburg.de\/wordpress\/wp-json\/wp\/v2\/pages\/154\/revisions"}],"predecessor-version":[{"id":163,"href":"https:\/\/mfhohenlimburg.de\/wordpress\/wp-json\/wp\/v2\/pages\/154\/revisions\/163"}],"wp:attachment":[{"href":"https:\/\/mfhohenlimburg.de\/wordpress\/wp-json\/wp\/v2\/media?parent=154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}